{"id":74953,"date":"2026-05-13T12:32:08","date_gmt":"2026-05-13T12:32:08","guid":{"rendered":"https:\/\/pipsc.ca\/?p=74953"},"modified":"2026-05-13T12:32:08","modified_gmt":"2026-05-13T12:32:08","slug":"possibilite-de-benevolat-piquet-dinformation-sur-le-rab-dans-la-region-de-la-capitale-nationale","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/possibilite-de-benevolat-piquet-dinformation-sur-le-rab-dans-la-region-de-la-capitale-nationale\/","title":{"rendered":"Possibilit\u00e9 de b\u00e9n\u00e9volat\u00a0: Piquet d\u2019information sur le RAB dans la r\u00e9gion de la capitale nationale"},"content":{"rendered":"<div class=\"post-intro-box\">\n  <div class=\"intro-content\">\n    La mani\u00e8re dont le travail est effectu\u00e9 dans la fonction publique a chang\u00e9. Les membres de l\u2019Institut ont obtenu des r\u00e9sultats sous pression, se sont adapt\u00e9s rapidement et ont prouv\u00e9 que l\u2019on peut travailler efficacement n\u2019importe o\u00f9. \n  <\/div>\n  <div class=\"published-part text-sm text-gray-500 flex flex-wrap gap-2 items-center\">\n    <span>Publi\u00e9<\/span>\n    <time class=\"dt-published\" datetime=\"2026-05-13T12:32:08+00:00\">\n      May 13, 2026\n    <\/time>\n    <span> | <\/span>\n    <span>Derni\u00e8re mise \u00e0 jour<\/span>\n    <span class=\"text-gray-700 font-medium\">\n      il y a 3 heures\n    <\/span>\n  <\/div>\n<\/div>\n\n\n<div class=\"container\">\n<p>La mani\u00e8re dont le travail est effectu\u00e9 dans la fonction publique a chang\u00e9. Les membres de l\u2019Institut ont obtenu des r\u00e9sultats sous pression, se sont adapt\u00e9s rapidement et ont prouv\u00e9 que l\u2019<strong>on peut travailler efficacement n\u2019importe o\u00f9.&nbsp;<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Notre premier piquet sur le retour au bureau&nbsp;(RAB), organis\u00e9 le mois dernier au pr\u00e9 Tunney, a \u00e9t\u00e9 un grand succ\u00e8s, et nous avons besoin de votre aide pour continuer \u00e0 faire pression sur le gouvernement afin qu\u2019il suspende le mandat de RAB. Votre exp\u00e9rience en tant que membre \u00e0 la retraite est extr\u00eamement pr\u00e9cieuse dans ces conversations, et votre participation fait toute la diff\u00e9rence. Joignez-vous \u00e0 nous en tant que b\u00e9n\u00e9vole et&nbsp;:<\/p>\n<\/div>\n\n<div class=\"container\">\n<ul class=\"wp-block-list\"><div class=\"container\">\n<li>Accueillez les membres qui entrent sur le lieu de travail;<\/li>\n<\/div>\n\n<div class=\"container\">\n<li>Distribuez des d\u00e9pliants de campagne;<\/li>\n<\/div>\n\n<div class=\"container\">\n<li>Offrez du caf\u00e9 et des beignes;<\/li>\n<\/div>\n\n<div class=\"container\">\n<li>Encouragez les travailleur\u00b7ses \u00e0 envoyer un courriel \u00e0 leur d\u00e9put\u00e9\u00b7e pour suspendre le mandat de RAB.<\/li>\n<\/div><\/ul>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Jour de b\u00e9n\u00e9volat n<\/strong><strong><sup>o<\/sup><\/strong><strong>&nbsp;1<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Date et heure&nbsp;:<\/strong> Jeudi&nbsp;21&nbsp;mai, de 7&nbsp;h \u00e0 8&nbsp;h&nbsp;30<br><strong>Lieu&nbsp;:<\/strong> 22 Eddy (22 rue Eddy, Gatineau, QC J8X 2J9)<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong><a href=\"https:\/\/enaction.ipfpc.ca\/le_piquet_d_information_sur_le_rab_de_la_section_locale_de_la_rcn_de_la_gmr_21_mai\" target=\"_blank\" rel=\"noopener\">Je confirme ma pr\u00e9sence (21 mai)<\/a><\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Jour de b\u00e9n\u00e9volat n<\/strong><strong><sup>o<\/sup><\/strong><strong>&nbsp;2<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Date et heure&nbsp;: <\/strong>Jeudi&nbsp;28&nbsp;mai, de 12&nbsp;h \u00e0 13&nbsp;h<br><strong>Lieu&nbsp;:<\/strong> Ressources naturelles Canada (580, rue Booth, Ottawa, ON K1A 0Y7)<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong><a href=\"https:\/\/enaction.ipfpc.ca\/piquet_d_information_sur_le_rab_de_la_section_locale_de_la_rcn_de_la_gmr_28_mai\" target=\"_blank\" rel=\"noopener\">Je confirme ma pr\u00e9sence (28 mai)<\/a><\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Jour de b\u00e9n\u00e9volat n<\/strong><strong><sup>o<\/sup><\/strong><strong>&nbsp;3<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Date et heure&nbsp;: <\/strong>Mercredi&nbsp;3&nbsp;juin, de 7&nbsp;h \u00e0 8&nbsp;h&nbsp;30<br><strong>Lieu&nbsp;:<\/strong> Place Vincent Massey (351, boulevard Saint-Joseph, Gatineau, QC J8Y 3Z4)<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong><a href=\"https:\/\/enaction.ipfpc.ca\/piquet_d_information_sur_le_rab_3_juin\" target=\"_blank\" rel=\"noopener\">Je confirme ma pr\u00e9sence (3 juin)<\/a><\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Veuillez noter que les frais kilom\u00e9triques, de stationnement et autres ne peuvent pas \u00eatre rembours\u00e9s pour cet \u00e9v\u00e9nement. Merci de votre solidarit\u00e9 et de votre appui continus. Pour toute question, veuillez nous \u00e9crire \u00e0 <a href=\"mailto:bienmieuxensemble@ipfpc.ca\"><strong>bienmieuxensemble@ipfpc.ca<\/strong><\/a>.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La mani\u00e8re dont le travail est effectu\u00e9 dans la fonction publique a chang\u00e9. Les membres de l\u2019Institut ont obtenu des r\u00e9sultats sous pression, se sont adapt\u00e9s rapidement et ont prouv\u00e9 que l\u2019on peut travailler efficacement n\u2019importe o\u00f9.&nbsp; Notre premier piquet sur le retour au bureau&nbsp;(RAB), organis\u00e9 le mois dernier au pr\u00e9 Tunney, a \u00e9t\u00e9 un &hellip;<\/p>\n","protected":false},"author":10000133408,"featured_media":72997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[55,2529,61],"group":[],"region":[],"employer":[],"chapter":[],"class_list":["post-74953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annonces","category-nouvelles","category-retour-sur-le-lieu-de-travail"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/74953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/10000133408"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=74953"}],"version-history":[{"count":2,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/74953\/revisions"}],"predecessor-version":[{"id":75027,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/74953\/revisions\/75027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media\/72997"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=74953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=74953"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=74953"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=74953"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=74953"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=74953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}