{"id":66999,"date":"2026-03-12T23:42:04","date_gmt":"2026-03-12T23:42:04","guid":{"rendered":"https:\/\/pipsc.ca\/?p=66999"},"modified":"2026-03-12T23:42:09","modified_gmt":"2026-03-12T23:42:09","slug":"proces-verbal-de-laga-de-la-gmr-region-de-rgt-15-octobre-2025","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/proces-verbal-de-laga-de-la-gmr-region-de-rgt-15-octobre-2025\/","title":{"rendered":"Proc\u00e8s-verbal de l&#8217;AGA de la GMR r\u00e9gion de RGT &#8211; 15 octobre 2025"},"content":{"rendered":"<div class=\"post-intro-box\">\n  <div class=\"intro-content\">\n    L\u2019Institut professionnel de la fonction publique du Canada\r\n\r\nThe Professional Institute of the Public Service of Canada\r\n\r\nSection de la r\u00e9gion du Grand Toronto (RGT) de la Guilde des membres retrait\u00e9\u00b7es \r\n\r\nProc\u00e8s-verbal de la 11e assembl\u00e9e g\u00e9n\u00e9rale annuelle\r\n\r\n15 octobre 2025 \u2014 Restaurant Pickle Barrel, Toronto\n  <\/div>\n  <div class=\"published-part text-sm text-gray-500 flex flex-wrap gap-2 items-center\">\n    <span>Publi\u00e9<\/span>\n    <time class=\"dt-published\" datetime=\"2026-03-12T23:42:04+00:00\">\n      mars 12, 2026\n    <\/time>\n    <span> | <\/span>\n    <span>Derni\u00e8re mise \u00e0 jour<\/span>\n    <span class=\"text-gray-700 font-medium\">\n      il y a 2 mois\n    <\/span>\n  <\/div>\n<\/div>\n\n\n<div class=\"container\">\n<p><strong>Sont pr\u00e9sent\u00b7es&nbsp;: Ex\u00e9cutif<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Pr\u00e9sident&nbsp;: Aron Wolfson<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Vice-pr\u00e9sidente&nbsp;: Andrea Agh<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Tr\u00e9sorier&nbsp;: Lester Brown<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Secr\u00e9taire&nbsp;: Soon Yee<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Membre actif&nbsp;: Usha Vashistha<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Sont pr\u00e9sent\u00b7es&nbsp;: 33&nbsp;membres<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>La r\u00e9union commence \u00e0 midi.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Ouverture de la r\u00e9union&nbsp;<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Aron Wolfson souhaite la bienvenue \u00e0 tout le monde et pr\u00e9sente l\u2019ex\u00e9cutif de la section de la RGT. Elle pr\u00e9sente \u00e9galement Kim Scriver, pr\u00e9sidente de la GMR, et Stan Buday, repr\u00e9sentant de la GMR pour l\u2019Ontario.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Aron mentionne que Fred Conway a d\u00e9missionn\u00e9 l\u2019ann\u00e9e derni\u00e8re de son poste de membre actif de la section de la RGT. Il a \u00e9t\u00e9 r\u00e9compens\u00e9 pour ses neuf ann\u00e9es de service d\u00e9vou\u00e9 \u00e0 la section.<br>&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Aron \u00e9voque le succ\u00e8s du premier \u00e9v\u00e9nement social de la section de la RGT qui s\u2019est d\u00e9roul\u00e9 au restaurant Sababa le 15 ao\u00fbt 2025. Dix-huit personnes y ont particip\u00e9 et le co\u00fbt total est rest\u00e9 dans les limites du budget pr\u00e9vu. Nous attendons avec impatience le prochain \u00e9v\u00e9nement social. Aron accueille favorablement les suggestions des participant\u00b7es concernant d\u2019autres lieux pour l\u2019\u00e9v\u00e9nement social de l\u2019ann\u00e9e prochaine.<br>&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Ordre du jour<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Tom Belyk propose l\u2019adoption de l\u2019ordre du jour. Nasrin Haji appuie la motion. Motion adopt\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>CONF\u00c9RENCI\u00c8RE PRINCIPALE<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>La conf\u00e9renci\u00e8re principale est Kim Scriver, pr\u00e9sidente de la GMR. Elle fait \u00e9galement partie de l\u2019ex\u00e9cutif de la section de la r\u00e9gion de la capitale nationale de la GMR.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Elle a indiqu\u00e9 que les postes de pr\u00e9sident\u00b7e, de vice-pr\u00e9sident\u00b7e et de tr\u00e9sorier\u00b7\u00e8re du bureau national de la GMR peuvent sembler changer d\u2019une ann\u00e9e \u00e0 l\u2019autre parce que des \u00e9lections sont organis\u00e9es chaque ann\u00e9e pour ces trois postes. Il est propos\u00e9 d\u2019organiser des \u00e9lections tous les deux ans pour ces postes.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Lors de l\u2019AGA nationale de l\u2019Institut qui s\u2019est tenue l\u2019ann\u00e9e derni\u00e8re \u00e0 Toronto, la d\u00e9l\u00e9gation de la GMR s\u2019est oppos\u00e9e en vain \u00e0 l\u2019augmentation des cotisations de 16&nbsp;dollars \u00e0 compter de janvier 2025. L\u2019augmentation des cotisations a ensuite entra\u00een\u00e9 la d\u00e9mission de 53 membres identifiables de la GMR.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Le d\u00e9fi du recrutement de nouveaux membres reste d\u2019actualit\u00e9. Par exemple, les nouveaux et nouvelles retrait\u00e9\u00b7es deviennent automatiquement membres de la GMR l\u2019ann\u00e9e de leur d\u00e9part \u00e0 la retraite et restent membres jusqu\u2019au 31 d\u00e9cembre de cette m\u00eame ann\u00e9e sans payer de cotisation. Le d\u00e9fi consiste \u00e0 les convaincre de rester membres cotisants \u00e0 l\u2019avenir. Les participant\u00b7es ont sugg\u00e9r\u00e9 de mieux communiquer avec ces nouveaux retrait\u00e9s sur les avantages qu\u2019ils ont \u00e0 rester membres, par exemple en plaidant pour l\u2019am\u00e9lioration du RSDP et l\u2019acc\u00e8s au programme Service Plus.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><br>La campagne de cartes postales du RSDP, lanc\u00e9e par Andrea Agh, vice-pr\u00e9sidente de la section de la RGT de la GMR, a \u00e9t\u00e9 pleinement approuv\u00e9e par l\u2019ex\u00e9cutif national de la Guilde. Le concept sera trait\u00e9 plus en d\u00e9tail avec d\u2019autres sections de la GMR dans le pays. Kim insiste sur le fait que la GMR travaille avec l\u2019ANRF et la soutient, et non contre elle. Elle recommande \u00e9galement que nous prenions contact avec l\u2019Association des syndicalistes \u00e0 la retraite du Canada (ASRC) au sujet de notre action en faveur du RSDP. L\u2019ASRC est membre du Congr\u00e8s du travail du Canada.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Kim ajoute que chaque ann\u00e9e, le bureau national de la GMR alloue des fonds aux diff\u00e9rentes sections de la GMR \u00e0 travers le Canada. L\u2019allocation annuelle minimale est pass\u00e9e de 800 \u00e0 1&nbsp;200&nbsp;dollars. D\u2019une mani\u00e8re g\u00e9n\u00e9rale, une section peut demander un financement sup\u00e9rieur au montant minimum, accompagn\u00e9 d\u2019une justification appropri\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Kim mentionne que l\u2019AGA nationale de la GMR se tiendra le 11 d\u00e9cembre \u00e0 l\u2019h\u00f4tel Sheraton, au centre-ville de Toronto. L\u2019heure de d\u00e9part est fix\u00e9e \u00e0 13 heures, suivie d\u2019une rencontre sociale \u00e0 16&nbsp;h&nbsp;30. Les personnes int\u00e9ress\u00e9es \u00e0 y participer recevront prochainement une invitation par courriel. Kim a confirm\u00e9 que les participant\u00b7es pourront voter lors de la r\u00e9union. Pour la premi\u00e8re fois, l\u2019AGA de la GMR sera une r\u00e9union hybride, c\u2019est-\u00e0-dire que nos membres pourront y assister en personne ou en ligne virtuellement. L\u2019ordre du jour comprendra une discussion sur les motions propos\u00e9es par le Bureau national de l\u2019Institut ainsi que sur les motions propos\u00e9es par le Bureau national de la GMR, telles que la modification du mandat du\/de la pr\u00e9sident\u00b7e, du\/de la vice-pr\u00e9sident\u00b7e et du\/de la tr\u00e9sorier\u00b7\u00e8re, qui passerait de 1 an \u00e0 2 ans, comme nous l\u2019avons d\u00e9j\u00e0 mentionn\u00e9.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>L\u2019AGA nationale de l\u2019IPFPC se tiendra au centre-ville de Toronto, \u00e0 l\u2019h\u00f4tel Sheraton, les 12 et 13 d\u00e9cembre. Seuls certains membres y seront invit\u00e9s. La GMR aura des repr\u00e9sentants \u00e0 cette assembl\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Campagne de cartes postales sur le RSDP (R\u00e9gime de services dentaires pour les retrait\u00e9s)<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Andrea Agh m\u00e8ne une discussion sur la nouvelle \u00ab&nbsp;carte postale&nbsp;\u00bb qu\u2019elle a con\u00e7ue pour le r\u00e9gime dentaire. C\u2019est la deuxi\u00e8me fois que la section de la RGT tente d\u2019adresser une p\u00e9tition aux d\u00e9put\u00e9s pour qu\u2019ils am\u00e9liorent notre r\u00e9gime de soins dentaires. La premi\u00e8re tentative a eu lieu l\u2019ann\u00e9e derni\u00e8re et nous avions demand\u00e9 \u00e0 nos membres d\u2019envoyer par courriel une p\u00e9tition pr\u00e9par\u00e9e \u00e0 leur d\u00e9put\u00e9. Un vote \u00e0 main lev\u00e9e lors de l\u2019AGA 2024 a indiqu\u00e9 que seuls 8 des 33 membres avaient envoy\u00e9 la lettre de p\u00e9tition \u00e0 leur d\u00e9put\u00e9, un chiffre quelque peu d\u00e9cevant.&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>L\u2019ex\u00e9cutif de la section de la RGT encourage ses membres \u00e0 maintenir la pression sur le gouvernement f\u00e9d\u00e9ral en leur demandant d\u2019envoyer la nouvelle carte postale \u00e0 leur d\u00e9put\u00e9.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Le plafond annuel de 1&nbsp;500&nbsp;dollars pr\u00e9vu par le RSDP a \u00e9t\u00e9 fix\u00e9 en 2001 et n\u2019a pas \u00e9t\u00e9 augment\u00e9 depuis lors, tandis que la prime d\u2019assurance dentaire a augment\u00e9 \u00e0 plusieurs reprises, y compris l\u2019ann\u00e9e derni\u00e8re. Le plafond annuel de remboursement du RSDFP (le r\u00e9gime de soins dentaires de nos membres qui travaillent) a augment\u00e9 au fil des ans pour atteindre environ 3&nbsp;200&nbsp;$. L\u2019in\u00e9galit\u00e9 persiste.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>La nouvelle \u00ab&nbsp;carte postale&nbsp;\u00bb est une version condens\u00e9e de la lettre de p\u00e9tition de l\u2019ann\u00e9e derni\u00e8re, mais elle est plus graphique.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Le th\u00e8me g\u00e9n\u00e9ral v\u00e9hicul\u00e9 par la carte postale est qu\u2019il y a un d\u00e9calage entre la couverture du RSDP et celle du RSDFP. Nous recherchons l\u2019\u00e9quit\u00e9 entre les deux r\u00e9gimes.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><br>La carte postale \u00e9num\u00e8re quatre points&nbsp;:<\/p>\n<\/div>\n\n<div class=\"container\">\n<ul class=\"wp-block-list\"><div class=\"container\">\n<li>Am\u00e9liorer le RSDP pour qu\u2019il corresponde au niveau des prestations du RSDFP<\/li>\n<\/div>\n\n<div class=\"container\">\n<li>Combler cette lacune de longue date dans les soins de sant\u00e9 des retrait\u00e9s<\/li>\n<\/div>\n\n<div class=\"container\">\n<li>Honorer les services rendus par les fonctionnaires retrait\u00e9s en leur offrant une couverture dentaire \u00e9quitable<\/li>\n<\/div>\n\n<div class=\"container\">\n<li>Combiner le RSDFP et le RSDFP en un seul r\u00e9gime<\/li>\n<\/div><\/ul>\n<\/div>\n\n<div class=\"container\">\n<p>La carte postale comporte une ligne de signature pour le membre ainsi qu\u2019une liste de cinq d\u00e9put\u00e9s \u00e0 qui la carte peut \u00eatre envoy\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><br>La section de la RGT souhaite remercier l\u2019\u00e9quipe nationale de la GMR pour son soutien \u00e0 la p\u00e9tition sur le RSDP et plus particuli\u00e8rement Kim Scriver pour ses efforts en vue de la traduction et de l\u2019impression de la carte postale.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>L\u2019obstacle actuel est que les cartes postales qui ont \u00e9t\u00e9 imprim\u00e9es par notre Bureau national et pr\u00e9sent\u00e9es lors de la r\u00e9union \u00e9taient un peu plus grandes que pr\u00e9vu (8,5 x 11 pouces) et un peu difficiles \u00e0 manipuler pour nos besoins. &nbsp; Nous avions demand\u00e9 des cartes de la taille d\u2019une carte postale que les participants auraient pu signer lors de l\u2019AGA, et qui auraient \u00e9t\u00e9 collect\u00e9es par Andrea et ensuite envoy\u00e9es en masse au(x) d\u00e9put\u00e9(s).<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Cependant, Andrea essaiera d\u2019obtenir des cartes postales plus petites et \u00e9tudiera ensuite les moyens de les distribuer \u00e0 nos membres pour qu\u2019ils les signent et les envoient ensuite \u00e0 leurs d\u00e9put\u00e9s.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Les membres ont manifest\u00e9 un int\u00e9r\u00eat consid\u00e9rable, comme en t\u00e9moignent les questions qui ont suivi.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Il a \u00e9t\u00e9 soulign\u00e9 que nos membres ne sont pas admissibles au r\u00e9gime public de soins dentaires en raison de leur \u00ab&nbsp;acc\u00e8s&nbsp;\u00bb au RSDP. &nbsp; Le r\u00e9gime public de soins dentaires ne pr\u00e9voit pas de limite annuelle pour les demandes de remboursement, tandis que le RSDP pr\u00e9voit une limite annuelle de 1&nbsp;500&nbsp;$. Cette situation est manifestement in\u00e9quitable.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Un membre a indiqu\u00e9 que l\u2019assureur avait refus\u00e9 sa demande de remboursement de frais dentaires alors qu\u2019elle avait pr\u00e9sent\u00e9 une facture contenant une description d\u2019une ligne d\u2019un service dentaire. Elle a ensuite pr\u00e9sent\u00e9 une facture d\u00e9taill\u00e9e pour le m\u00eame service, ce qui a donn\u00e9 lieu \u00e0 un remboursement partiel. La partie non rembours\u00e9e de la d\u00e9pense est alors consid\u00e9r\u00e9e comme une d\u00e9pense m\u00e9dicale \u00e0 des fins fiscales.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Un autre membre a d\u00e9crit la situation inverse&nbsp;: il a pr\u00e9sent\u00e9 une facture d\u00e9taill\u00e9e pour un service m\u00e9dical. La demande a d\u2019abord \u00e9t\u00e9 refus\u00e9e, mais apr\u00e8s la soumission d\u2019une description d\u2019une ligne du service m\u00e9dical, la demande a \u00e9t\u00e9 accept\u00e9e. La conclusion serait de tenter une deuxi\u00e8me approche (description d\u00e9taill\u00e9e ou description d\u2019une seule ligne, selon le cas) si la demande des membres est refus\u00e9e dans un premier temps.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Approbation du proc\u00e8s-verbal de la derni\u00e8re AGA (18&nbsp;novembre 2024)<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Le secr\u00e9taire, Soon Yee, a envoy\u00e9 par courriel des copies du proc\u00e8s-verbal \u00e0 tous les participant\u00b7es avant la r\u00e9union. Paul Archibald propose que le budget de 2024 soit accept\u00e9, avec l\u2019appui d\u2019Al Worth. Motion adopt\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Rapport de tr\u00e9sorerie<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Le tr\u00e9sorier, Les Brown, traite des \u00e9tats financiers de 2024 et du budget de 2026, dont des copies ont \u00e9t\u00e9 envoy\u00e9es par courriel \u00e0 tous les participant\u00b7es avant la r\u00e9union. Al Worth propose d\u2019accepter les \u00e9tats financiers et le budget, appuy\u00e9 par Sheldon Weiser. Motion adopt\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>\u00c9lections&nbsp;<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Les Brown proc\u00e8de \u00e0 l\u2019\u00e9lection en tant que pr\u00e9sident du Comit\u00e9 des \u00e9lections.&nbsp;&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Poste de pr\u00e9sident\u00b7e de la section de la RGT<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Il y a deux candidatures pour ce poste. Nusin Brown a propos\u00e9 Andrea Agh et Aron Wolfson a propos\u00e9 Lalita Jeethan, in absentia. Aron lit la note biographique de Lalita qui lui a \u00e9t\u00e9 fournie par cette derni\u00e8re avant la r\u00e9union. Lalita se dit int\u00e9ress\u00e9e par le poste de vice-pr\u00e9sident\u00b7e ou par celui de membre actif\u00b7ve. Andrea Agh pr\u00e9sente ensuite sa note biographique. Merci \u00e0 Alice DaSilva pour la collecte des bulletins de vote et \u00e0 Stan Buday et Nusin Brown pour le d\u00e9pouillement. Andrea Agh est \u00e9lue vice-pr\u00e9sidente.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Les Brown propose que les bulletins de vote soient d\u00e9truits. Adele Minini l\u2019appuie. Motion adopt\u00e9e.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Poste de membre actif de la section de la RGT<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Deux postes de membres actifs \u00e9taient vacants. Soon Yee propose la candidature de Usha Vashistha. Nusin Brown propose la candidature de Lalita Jeethan, in absentia. Il n\u2019y a pas d\u2019autres candidatures et Usha Vashistha et Lalita Jeethan sont ainsi \u00e9lues membres actives par acclamation.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Affaires nouvelles<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>\u00c0 l\u2019AGA de l\u2019an dernier, un\u00b7e membre a demand\u00e9 qu\u2019une discussion sur ServicePlus et d\u2019autres avantages de la GMR ait lieu lors de la prochaine AGA. Cette discussion est li\u00e9e au d\u00e9fi de la fid\u00e9lisation des membres \u00e9voqu\u00e9 par Kim Scriver ci-dessus.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>En raison de notre programme charg\u00e9 cette ann\u00e9e, en particulier avec les \u00e9lections, nous n\u2019avons pas \u00e9t\u00e9 en mesure d\u2019organiser cette discussion lors de l\u2019AGA de cette ann\u00e9e, mais Andrea a sugg\u00e9r\u00e9 que nous nous adressions \u00e0 HO pour organiser une pr\u00e9sentation virtuelle de Service Plus, \u00e0 laquelle les membres pourraient se connecter et assister \u00e0 leur guise.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Tirage au sort<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Andrea Agh proc\u00e8de au tirage au sort des prix de pr\u00e9sence. Cinq cartes Tim Horton\u2019s de 10&nbsp;dollars sont tir\u00e9es au sort. Merci \u00e0 Kim Scriver d\u2019avoir fourni des sacs fourre-tout en guise de prix suppl\u00e9mentaires.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p><strong>Lev\u00e9e de la s\u00e9ance<\/strong><\/p>\n<\/div>\n\n<div class=\"container\">\n<p>La s\u00e9ance est lev\u00e9e \u00e0 14&nbsp;h&nbsp;30 environ.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Sont pr\u00e9sent\u00b7es&nbsp;: Ex\u00e9cutif Pr\u00e9sident&nbsp;: Aron Wolfson Vice-pr\u00e9sidente&nbsp;: Andrea Agh Tr\u00e9sorier&nbsp;: Lester Brown Secr\u00e9taire&nbsp;: Soon Yee Membre actif&nbsp;: Usha Vashistha Sont pr\u00e9sent\u00b7es&nbsp;: 33&nbsp;membres La r\u00e9union commence \u00e0 midi. Ouverture de la r\u00e9union&nbsp; Aron Wolfson souhaite la bienvenue \u00e0 tout le monde et pr\u00e9sente l\u2019ex\u00e9cutif de la section de la RGT. Elle pr\u00e9sente \u00e9galement Kim Scriver, pr\u00e9sidente &hellip;<\/p>\n","protected":false},"author":10000058516,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"group":[160],"region":[],"employer":[],"chapter":[],"class_list":["post-66999","post","type-post","status-publish","format-standard","hentry","category-non-categorise","group-guilde-des-membres-retraites-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/66999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/10000058516"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=66999"}],"version-history":[{"count":1,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/66999\/revisions"}],"predecessor-version":[{"id":67000,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/66999\/revisions\/67000"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=66999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=66999"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=66999"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=66999"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=66999"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=66999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}