{"id":61533,"date":"2019-07-18T00:00:00","date_gmt":"2019-07-18T00:00:00","guid":{"rendered":"https:\/\/pipsc.ca\/grc-conditions-de-travail-comparees-resultat\/"},"modified":"2019-07-18T00:00:00","modified_gmt":"2019-07-18T00:00:00","slug":"grc-conditions-de-travail-comparees-resultat","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/grc-conditions-de-travail-comparees-resultat\/","title":{"rendered":"GRC &#8211; Conditions de travail compar\u00e9es &#8211; R\u00e9sultat"},"content":{"rendered":"<div class=\"container\">\n<h2><strong>Quelques mots sur le tableau comparatif<\/strong><\/h2>\n\n<p>Le tableau ci-dessous ne contient pas toutes les dispositions des conventions collectives qui ne trouvent pas leur \u00e9quivalent dans les conditions de travail de la GRC. Il ne vise qu\u2019\u00e0 servir de guide aux membres civils de l\u2019IPFPC et ne refl\u00e8te peut-\u00eatre pas fid\u00e8lement les diff\u00e9rences entre membres civils dans d\u2019autres syndicats. De plus, la liste n\u2019est pas exhaustive et ne montre pas toutes les diff\u00e9rences entre les documents sources. Pour conna\u00eetre les r\u00e9f\u00e9rences exactes, les utilisateurs devraient consulter les documents sources pertinents (politiques\/manuels de la GRC et conventions collectives applicables).<\/p>\n\n<p>Des questions ou des commentaires? Veuillez nous en faire part \u00e0 <a href=\"mailto:civilian_members@pipsc.ca\">civilian_members@pipsc.ca<\/a>.<\/p>\n\n<h3>Tableau comparatif des conditions de travail &#8211; R\u00c9SULTAT<\/h3>\n\n<hr \/>\n<h3>A) Dur\u00e9e du travail<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>40 heures par semaine comprenant 30 minutes par jour de pause-repas pay\u00e9es<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>37,5 heures par semaine, sans compter 30 minutes par jour de pause-repas non pay\u00e9es<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>B) Pause-repas<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>30 minutes de pause-repas pay\u00e9es au taux de r\u00e9mun\u00e9ration horaire normal<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>30 minutes de pause-repas non pay\u00e9es<\/p>\n\n<p>\u2013 Les heures suppl\u00e9mentaires s\u2019appliquent lorsque les membres doivent travailler pendant la pause-repas<\/p>\n\n<p>\u2013 Deux pauses-sant\u00e9 r\u00e9mun\u00e9r\u00e9es de quinze minutes (selon la convention collective)<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>C) Jours f\u00e9ri\u00e9s d\u00e9sign\u00e9s pay\u00e9s<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>11 jours f\u00e9ri\u00e9s d\u00e9sign\u00e9s pay\u00e9s<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>M\u00eame chose + un autre jour lorsqu\u2019une loi du Parlement le proclame comme jour f\u00e9ri\u00e9 national<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>D) Horaires et quarts<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Les horaires sont affich\u00e9s 28 jours d\u2019avance.<\/p>\n\n<p>\u2013 Les horaires sont faits pour au moins 28 jours civils cons\u00e9cutifs.<\/p>\n\n<p>Les quarts durent entre 8 et 12 heures.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Les horaires sont affich\u00e9s 21 jours d\u2019avance.<br \/>\n\u2013 Les horaires sont faits pour au moins 28 jours civils cons\u00e9cutifs et au plus 2 mois d\u2019avance.<br \/>\nLes quarts durent entre 7 et 9 heures.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>E) Cong\u00e9s compensatoires<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 Limite ferme de 80 heures accumul\u00e9es, qui peuvent \u00eatre report\u00e9es ind\u00e9finiment<\/p>\n\n<p>-160 heures accumul\u00e9es dans le cas des postes pour une dur\u00e9e limit\u00e9e ou des postes isol\u00e9s<br \/>\n\u2013 L\u2019indemnit\u00e9 est calcul\u00e9e en fonction du taux de r\u00e9mun\u00e9ration du poste d\u2019attache au 31 mars de l\u2019exercice pr\u00e9c\u00e9dent.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Il n\u2019y a pas de limite ferme pour ces heures accumul\u00e9es, mais les heures qui d\u00e9passent 37,5 heures doivent \u00eatre encaiss\u00e9es au plus tard le 30 septembre, au taux horaire du 31 mars de l\u2019exercice pr\u00e9c\u00e9dent (selon la convention collective).<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n\t<li>Les cr\u00e9dits seront maintenus aux niveaux en vigueur au moment de la conversion et ne seront pas calcul\u00e9s au prorata pour tenir compte du passage d\u2019une semaine de travail de 40 heures \u00e0 une semaine de travail de 37,5 heures.<\/li>\n\t<li>Les dispositions relatives au report maximal autoris\u00e9 dans la convention collective ne s\u2019appliqueront pas avant le 31 mars 2021, et les montants exc\u00e9dentaires seront pay\u00e9s au nouveau taux horaire.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>F) Disponibilit\u00e9 op\u00e9rationnelle (DO)<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>1 heure pay\u00e9e pour chaque p\u00e9riode de disponibilit\u00e9 op\u00e9rationnelle de 8 heures<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Semblable (0,5 heure pay\u00e9e pour chaque p\u00e9riode de disponibilit\u00e9 de 4 heures)<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>Les primes de disponibilit\u00e9 (DO et EPO) ne s\u2019appliquent plus aux membres civils (MC).<\/li>\n\t<li>Les MC qui doivent \u00eatre en disponibilit\u00e9 (DO) en dehors des heures de service seront r\u00e9mun\u00e9r\u00e9s conform\u00e9ment aux dispositions de la convention collective relatives \u00e0 la disponibilit\u00e9.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>G) \u00c9tat de pr\u00e9paration op\u00e9rationnelle (EPO)<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>1 heure pay\u00e9e pour chaque p\u00e9riode de disponibilit\u00e9 op\u00e9rationnelle de 4 heures<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Il n\u2019y a pas de disposition \u00e0 cet \u00e9gard.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>Les CM qui doivent \u00eatre en disponibilit\u00e9 (DO) en dehors des heures de service seront r\u00e9mun\u00e9r\u00e9s conform\u00e9ment aux dispositions de la convention collective relatives \u00e0 la disponibilit\u00e9.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>H) Heures suppl\u00e9mentaires<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 Les heures suppl\u00e9mentaires sont r\u00e9mun\u00e9r\u00e9es au taux horaire normal et demi (1 \u00bd) ou au taux double (2) et demi (2 \u00bd) pour chaque heure suppl\u00e9mentaire effectu\u00e9e, ou elles sont compens\u00e9es en cong\u00e9 ordinaire ou en temps libre pay\u00e9.<br \/>\n\u2013 La r\u00e9mun\u00e9ration des heures suppl\u00e9mentaires effectu\u00e9es durant un temps libre pay\u00e9 est calcul\u00e9e au taux horaire normal et demi (1 \u00bd).<br \/>\n\u2013 La r\u00e9mun\u00e9ration des heures suppl\u00e9mentaires effectu\u00e9es durant un cong\u00e9 ordinaire ou les premier et deuxi\u00e8me jours de rappel au travail pendant le cong\u00e9 annuel ou le cong\u00e9 compensatoire est calcul\u00e9e au double du taux horaire normal.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013 Les heures suppl\u00e9mentaires sont r\u00e9mun\u00e9r\u00e9es au taux horaire normal et demi (1 \u00bd) ou au taux double (2) et demi (2 \u00bd) selon leur nombre, le fait que c\u2019est un jour de repos, etc.<\/p>\n\n<p>\u2013 Taux de r\u00e9mun\u00e9ration horaire plus \u00e9lev\u00e9 (6,67 %) pour le calcul des heures suppl\u00e9mentaires<\/p>\n\n<p>\u2013 Les membres peuvent avoir le droit de faire des heures suppl\u00e9mentaires au double du taux de r\u00e9mun\u00e9ration s\u2019ils travaillent plus de 7,5 heures suppl\u00e9mentaires un jour de travail normal, plus de 7,5 heures le premier jour de repos ou s\u2019ils travaillent le deuxi\u00e8me jour cons\u00e9cutif de repos et les jours de repos suivants.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>I) Rappel au travail<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Minimum de 3 heures pay\u00e9es au taux applicable en cas de rappel au travail apr\u00e8s le quart pr\u00e9vu<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Minimum de 3 heures pay\u00e9es au taux applicable en cas de rappel au travail apr\u00e8s le quart pr\u00e9vu<\/p>\n\n<p>\u2013 Selon la convention collective, sous r\u00e9serve d\u2019une limite de 8 heures pay\u00e9es pour une p\u00e9riode de 8 heures ou de la r\u00e9mun\u00e9ration au taux des heures suppl\u00e9mentaires applicable pour les heures travaill\u00e9es, le plus \u00e9lev\u00e9 des deux montants \u00e9tant retenu<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>J) Dispositions relatives \u00e0 la comparution<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 Devoir de comparution : Si la comparution survient au cours d\u2019un quart de travail normal, les membres sont r\u00e9mun\u00e9r\u00e9s au taux normal de r\u00e9mun\u00e9ration. S\u2019ils doivent compara\u00eetre en dehors de leur quart de travail normal, ils sont r\u00e9mun\u00e9r\u00e9s au taux des heures suppl\u00e9mentaires.<br \/>\n\u2013 Cong\u00e9 pay\u00e9 pour comparution : M\u00eame chose que pour le CT-IPFPC<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Le cong\u00e9 pay\u00e9 pour comparution est disponible pour des comparutions non li\u00e9es \u00e0 l\u2019emploi (p. ex. une comparution comme t\u00e9moin).<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>Les MC tenus de se rendre au tribunal ou d\u2019y assister pour des raisons li\u00e9es \u00e0 l\u2019exercice de leurs fonctions autoris\u00e9es (c.-\u00e0-d. des raisons non personnelles) sont consid\u00e9r\u00e9s comme \u00e9tant en service au taux applicable.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>K) Prime de jours f\u00e9ri\u00e9s d\u00e9sign\u00e9s pay\u00e9s<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 R\u00e9mun\u00e9ration au taux normal plus une prime de 1,5 fois le taux horaire normal pour toutes les heures travaill\u00e9es un jour f\u00e9ri\u00e9 d\u00e9sign\u00e9 pay\u00e9<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>R\u00e9mun\u00e9ration au taux normal plus prime de 1,5 fois le taux horaire normal pour les 7,5 premi\u00e8res heures d\u2019un quart de travail et r\u00e9mun\u00e9ration au taux horaire double par la suite, ou au taux horaire double pour toutes les heures suppl\u00e9mentaires effectu\u00e9es un jour f\u00e9ri\u00e9 accol\u00e9 \u00e0 un jour de repos.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>L) Prime li\u00e9e aux pauses-repas<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 La prime est \u00e9gale au taux horaire normal et demi pour la dur\u00e9e de la pause-repas qui n\u2019a pas \u00e9t\u00e9 prise.<\/p>\n\n<p>\u2013 On y a droit toutes les quatre heures de travail en heures suppl\u00e9mentaires.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013 Une indemnit\u00e9 de repas de 10,50 $ ou de 12 $ (sauf si un repas gratuit est fourni) plus une prime d\u2019heures suppl\u00e9mentaires et une p\u00e9riode de repas pay\u00e9e d\u2019une dur\u00e9e raisonnable<\/p>\n\n<p>\u2013 On y a droit apr\u00e8s avoir effectu\u00e9 trois heures de travail suppl\u00e9mentaires, puis toutes les quatre heures par la suite.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>M) Prime de quart<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Une prime de quart de 2 $ l\u2019heure pour les heures travaill\u00e9es admissibles entre 16 h et 8 h<br \/>\n\u2013 Pas de prime de quart pour les heures suppl\u00e9mentaires<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Une prime de quart de 2 $ l\u2019heure pour chaque heure travaill\u00e9e entre 16 h et 8 h (y compris les heures suppl\u00e9mentaires)<\/p>\n\n<p>\u2013 2 $ de prime de fin de semaine par heure, incluant les heures suppl\u00e9mentaires, le samedi et le dimanche<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>N) Affectations int\u00e9rimaires<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 P\u00e9riode d\u2019admissibilit\u00e9 : 5 jours cons\u00e9cutifs<br \/>\nLa dur\u00e9e de l\u2019affectation int\u00e9rimaire est limit\u00e9e \u00e0 4 ou 6 mois cons\u00e9cutifs, sous r\u00e9serve des exigences linguistiques et \u00e0 moins qu\u2019une prolongation soit autoris\u00e9e.<\/p>\n\n<p>La r\u00e9mun\u00e9ration provisoire n\u2019ouvre pas droit \u00e0 pension.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>P\u00e9riode d\u2019admissibilit\u00e9 : entre 3 et 5 jours cons\u00e9cutifs (selon la convention collective)<br \/>\nPas de dur\u00e9e d\u00e9termin\u00e9e avant la fin de l\u2019affectation int\u00e9rimaire, qui peut \u00eatre renouvel\u00e9e ind\u00e9finiment.<\/p>\n\n<p>La r\u00e9mun\u00e9ration provisoire ouvre droit \u00e0 pension.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>O) Cr\u00e9dits de cong\u00e9 annuel<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>0-5 ans de service 15 jours<\/p>\n\n<p>5-10 ans de service 20 jours<\/p>\n\n<p>10-23 ans de service 25 jours<\/p>\n\n<p>23 ans de service et plus 30 jours<\/p>\n\n<p>\u2013 Droit \u00e0 des cr\u00e9dits de cong\u00e9 annuel mensuels apr\u00e8s avoir \u00e9t\u00e9 pay\u00e9 pour au moins 8 heures dans un mois<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>0-8 ans de service 15 jours<\/p>\n\n<p>8-16 ans de service 20 jours<\/p>\n\n<p>16-17 ans de service 22 jours<\/p>\n\n<p>17-18 ans de service 23 jours<\/p>\n\n<p>18-27 ans de service 25 jours<\/p>\n\n<p>27-28 ans de service 27 jours<\/p>\n\n<p>28 ans de service et plus 30 jours<\/p>\n\n<p>\u2013 Droit \u00e0 des cr\u00e9dits de cong\u00e9 annuel mensuels apr\u00e8s avoir \u00e9t\u00e9 pay\u00e9 pour au moins 75 heures dans un mois<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique, mais les MC conserveront le taux d\u2019accumulation de cr\u00e9dits de cong\u00e9 en vigueur au moment de la conversion, jusqu\u2019\u00e0 leur prochaine augmentation d\u2019\u00e9chelon pr\u00e9vue dans la convention collective.<\/li>\n\t<li>De plus, la convention collective pr\u00e9voit deux (2) jours de cong\u00e9 personnel par ann\u00e9e et un cong\u00e9 annuel unique de cinq (5) jours.<\/li>\n\t<li>Un rajustement des cong\u00e9s annuels sera effectu\u00e9, et chaque MC se verra accorder un cong\u00e9 unique suppl\u00e9mentaire de quarante (40) heures.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>P) Cong\u00e9s annuels accumul\u00e9s<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Limite de 400 h (50 jours)<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Limite de 262,5 h (35 jours)<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique, mais les cr\u00e9dits seront maintenus aux niveaux en vigueur au moment de la conversion et ne seront pas calcul\u00e9s au prorata pour tenir compte du passage d\u2019une semaine de travail de 40 heures \u00e0 une semaine de travail de 37,5 heures.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>Q) Cong\u00e9 de compassion<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Cong\u00e9 de soignant : Limite de 5 jours, sauf que les membres de la GRC ont la possibilit\u00e9 d\u2019utiliser ce cong\u00e9 pour d\u00e9m\u00e9nager leur p\u00e8re ou leur m\u00e8re devenu(e) veuf\/veuve ou un fr\u00e8re ou une s\u0153ur devenu(e) orphelin(e).<br \/>\nCong\u00e9 de deuil : Maximum de 40 heures par deuil et aucun jour suppl\u00e9mentaire n\u2019est pr\u00e9vu pour les d\u00e9placements.<\/p>\n\n<p>Cong\u00e9 de soignant et de deuil : Limite de 80 heures par exercice financier, dont 40 peuvent \u00eatre utilis\u00e9es en cas de maladie dans la famille.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013 Cong\u00e9 de soignant : Limite de 5 jours, sauf que les membres de l\u2019IPFPC ont la possibilit\u00e9 d\u2019utiliser ce cong\u00e9 en cas de fermeture impr\u00e9vue de l\u2019\u00e9cole ou de la garderie.<\/p>\n\n<p>Cong\u00e9 de deuil : Au total, 7 jours civils cons\u00e9cutifs plus 3 jours pour les d\u00e9placements.<br \/>\nCong\u00e9 de soignant ou de deuil : la dur\u00e9e maximale diff\u00e8re selon le type de cong\u00e9, sans limite quant au nombre de cong\u00e9s de deuil dans une ann\u00e9e civile donn\u00e9e.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>R) Cong\u00e9s de maladie<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Pas d\u2019acquisition de cr\u00e9dits de cong\u00e9 de maladie. Les cong\u00e9s de maladie sont accord\u00e9s en fonction des besoins, sans limite \u00e9tablie. Un certificat m\u00e9dical est requis apr\u00e8s quatre jours cons\u00e9cutifs ou bien c\u2019est \u00e0 la discr\u00e9tion du superviseur.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013 R\u00e9gime actuel : Les cr\u00e9dits de cong\u00e9 de maladie sont acquis \u00e0 raison de neuf virgule trois sept cinq (9,375) heures par mois civil durant lequel l\u2019employ\u00e9 est pay\u00e9 pour avoir travaill\u00e9 au moins soixante-quinze (75) heures.<\/p>\n\n<p>\u2013 L\u2019IPFPC et le Conseil du Tr\u00e9sor ont conclu un protocole d\u2019entente concernant la cr\u00e9ation d\u2019un nouveau programme de soutien et de mieux-\u00eatre des employ\u00e9s (PSME). Le PSME propos\u00e9 met l\u2019accent sur l\u2019am\u00e9lioration du mieux-\u00eatre et la r\u00e9int\u00e9gration des employ\u00e9s au travail apr\u00e8s des p\u00e9riodes de cong\u00e9 pour cause de maladie ou de blessure. Les n\u00e9gociations entre l\u2019IPFPC et le Conseil du Tr\u00e9sor relativement au PSME se poursuivent et devraient bient\u00f4t prendre fin.<\/p>\n\n<p>Pour plus de d\u00e9tails et de nouvelles sur le PSME, cliquez ici : <a href=\"https:\/\/www.pipsc.ca\/fr\/nouvelles-et-enjeux\/conge-de-maladie\">Programme de soutien et de mieux-\u00eatre des employ\u00e9s de l\u2019IPFPC<\/a>.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique. Toutefois, au moment de la conversion, les MC se verront accorder une r\u00e9serve initiale de cong\u00e9s de maladie (selon la plus avantageuse des possibilit\u00e9s) :\n\t<ul>\n\t\t<li>Au moins 65 jours ou<\/li>\n\t\t<li>10 jours par ann\u00e9e de service (6,25 heures pour chaque mois de service complet)<\/li>\n\t<\/ul>\n\t<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>S) Cong\u00e9 pour les soins et l\u2019\u00e9ducation d\u2019enfants d\u2019\u00e2ge pr\u00e9scolaire (Cong\u00e9 non pay\u00e9 pour s\u2019occuper de la proche famille)<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 Limite de 5 ans au total pour la dur\u00e9e de service des membres<br \/>\n\u2013 Dur\u00e9e minimum de 6 mois pour chaque occurrence<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013 Limite de 5 ans au total pour la dur\u00e9e de service des membres \u2013 possibilit\u00e9 de d\u00e9passer cette limite quand l\u2019employ\u00e9 attend ses prestations de compassion de l\u2019assurance-emploi (AE)<br \/>\n\u2013 Dur\u00e9e minimum de 3 semaines pour chaque occurrence<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>T) Cong\u00e9s pour raisons personnelles<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 Droit \u00e0 un cong\u00e9 non pay\u00e9 pour raisons personnelles <em>une fois<\/em> pour la dur\u00e9e du service des membres, pour une p\u00e9riode maximale de 3 mois<\/p>\n\n<p>\u2013 Droit \u00e0 un cong\u00e9 non pay\u00e9 pour raisons personnelles <em>une fois<\/em> pour la dur\u00e9e du service des membres, pour une p\u00e9riode de plus de 3 mois mais de moins d\u2019un an<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013 Droit \u00e0 un cong\u00e9 non pay\u00e9 pour raisons personnelles <em>une ou deux fois<\/em> (selon la convention collective) pour la dur\u00e9e du service des membres, pour une p\u00e9riode maximale de 3 mois<\/p>\n\n<p>\u2013 Droit \u00e0 un cong\u00e9 non pay\u00e9 pour raisons personnelles <em>une ou deux fois<\/em> (selon la convention collective) pour la dur\u00e9e du service des membres, pour une p\u00e9riode de plus de 3 mois mais de moins d\u2019un an<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>U) Cong\u00e9 et indemnit\u00e9 de maternit\u00e9 et cong\u00e9 et indemnit\u00e9 parental(e)<\/h3>\n\n<h4>GRC \/ CT-IPFPC<\/h4>\n\n<p>\u2013 Maximum de 18 semaines cons\u00e9cutives de cong\u00e9 non pay\u00e9 pour un cong\u00e9 de maternit\u00e9 et maximum de 37 semaines cons\u00e9cutives de cong\u00e9 non pay\u00e9 pour un cong\u00e9 parental \u2013 ou un maximum combin\u00e9 de 52 semaines<\/p>\n\n<p>\u2013 \u00c0 condition d\u2019avoir travaill\u00e9 au moins 6 mois cons\u00e9cutifs avant le cong\u00e9 de maternit\u00e9 ou le cong\u00e9 parental, les membres ont droit \u00e0 une indemnit\u00e9 correspondant \u00e0 93 % de leur taux de r\u00e9mun\u00e9ration hebdomadaire, moins les prestations d\u2019AE ou du R\u00e9gime qu\u00e9b\u00e9cois d\u2019assurance parentale<\/p>\n\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n\n<hr \/>\n<h3>V) Dispositions relatives aux fun\u00e9railles et aux enterrements<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Les droits varient selon que le membre \u00e9tait employ\u00e9 ou retrait\u00e9 au moment de son d\u00e9c\u00e8s ou que le d\u00e9c\u00e8s est survenu dans l\u2019exercice de ses fonctions.<\/p>\n\n<p>Jusqu\u2019\u00e0 15 050 $ pour payer les fun\u00e9railles (les taux sont sujets \u00e0 r\u00e9vision par le secr\u00e9taire du SCT); possibilit\u00e9 d\u2019un suppl\u00e9ment de 7,9 % pour payer un deuxi\u00e8me directeur fun\u00e9raire<br \/>\nPossibilit\u00e9 d\u2019acheter une pierre tombale jusqu\u2019\u00e0 un maximum de 220 $ et la GRC en assurera l\u2019entretien \u00e0 perp\u00e9tuit\u00e9.<\/p>\n\n<p>Le lot ou la niche de columbarium sont gratuits pour les membres civils et les survivants admissibles dans les cimeti\u00e8res d\u00e9sign\u00e9s par la GRC.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Cette disposition n\u2019existe pas.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>Les MC conservent leur droit de b\u00e9n\u00e9ficier des dispositions relatives aux fun\u00e9railles et aux enterrements. \u00c0 la retraite, ces droits sont reconduits jusqu\u2019au d\u00e9c\u00e8s de l\u2019employ\u00e9.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>W) Indemnit\u00e9 de d\u00e9c\u00e8s<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Reste du salaire pour le mois du d\u00e9c\u00e8s et une gratification de d\u00e9c\u00e8s \u00e9quivalant \u00e0 2 mois de salaire (si le membre avait au moins 2 ans de service)<br \/>\nL\u2019admissibilit\u00e9 et les montants des prestations de survivant sont les m\u00eames en vertu du R\u00e9gime de revenu de survivant (RRS) et du R\u00e9gime de pension de retraite de la fonction publique (RPRFP).<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Reste du salaire pour le mois du d\u00e9c\u00e8s<\/p>\n\n<p>L\u2019admissibilit\u00e9 et les montants des prestations de survivant sont les m\u00eames en vertu du R\u00e9gime de revenu de survivant (RRS) et du R\u00e9gime de pension de retraite de la fonction publique (RPRFP).<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9 (l\u00e9gislation)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>X) R\u00e9installation<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>La Directive sur la r\u00e9installation de la GRC est semblable \u00e0 la Directive sur la r\u00e9installation du CNM, sauf quelques diff\u00e9rences mineures dans les prestations.<\/p>\n\n<p>Limite de deux ans pour faire une demande de remboursement.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Disposition d\u00e9crite dans la Directive sur la r\u00e9installation du CNM.<br \/>\nLimite de deux ans pour faire une demande de remboursement.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>Y) R\u00e9installation avant et apr\u00e8s le d\u00e9part \u00e0 la retraite<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Les d\u00e9penses de r\u00e9installation sont pay\u00e9es aux membres qui prennent leur retraite s\u2019ils ont \u00e9t\u00e9 r\u00e9install\u00e9s au cours de leur carri\u00e8re. la r\u00e9installation a lieu \u00e0 plus de quarante (40) kilom\u00e8tres de la r\u00e9sidence principale, \u00e0 moins qu\u2019il ne s\u2019agisse de quitter un logement appartenant \u00e0 l\u2019\u00c9tat.<br \/>\nLimite de deux ans pour faire une demande de remboursement.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Cette disposition n\u2019existe pas.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>Cette condition est conserv\u00e9e pour les personnes admissibles en raison d\u2019une r\u00e9installation qui a eu lieu avant la date de conversion.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>Z) Pensions<\/h3>\n\n<h4>GRC \/ CT-IPFPC<\/h4>\n\n<p>Quelle que soit leur date d\u2019entr\u00e9e en fonction \u00e0 la GRC (y compris les personnes embauch\u00e9es apr\u00e8s le 1er janvier 2013) et aussi longtemps qu\u2019ils continuent d\u2019\u00eatre employ\u00e9s dans la fonction publique, les membres civils seront r\u00e9put\u00e9s \u00eatre des contributeurs du groupe 1 du R\u00e9gime de pension de retraite de la fonction publique. Par cons\u00e9quent, l\u2019\u00e2ge de leur retraite normale demeure 60 ans. Cela veut dire que les membres civils int\u00e9gr\u00e9s sont admissibles aux prestations de retraite non r\u00e9duites payables \u00e0 60 ans s\u2019ils ont cumul\u00e9 au moins deux ans de service ouvrant droit \u00e0 pension, ou \u00e0 55 ans s\u2019ils ont au moins 30 ans de service ouvrant droit \u00e0 pension.<\/p>\n\n<p>Pour en savoir plus : article 387 de la <em>Loi no 2 sur le plan d\u2019action \u00e9conomique de 2014<\/em><\/p>\n\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9 (l\u00e9gislation)<\/li>\n<\/ul>\n\n<hr \/>\n<h3>AA) Prestations en vertu de la <em>Loi sur les pensions<\/em>, Anciens Combattants Canada (ACC)<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>ACC a le pouvoir exclusif de d\u00e9terminer si l\u2019\u00e9tat de sant\u00e9 ou le d\u00e9c\u00e8s du membre \u00e9tait attribuable au service \u00e0 la GRC ou aggrav\u00e9 par celui-ci, et dans quelle mesure l\u2019affection m\u00e9dicale ouvre droit \u00e0 pension.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Assur\u00e9es par la Commission provinciale des accidents du travail<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9 (l\u00e9gislation)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>AB) Assurance-invalidit\u00e9 et Invalidit\u00e9 de longue dur\u00e9e<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>\u2013 Prestation mensuelle \u00e9gale \u00e0 75 % de votre salaire mensuel brut en cas d\u2019invalidit\u00e9 totale et d\u2019incapacit\u00e9 de travail<\/p>\n\n<p>\u2013 Les employ\u00e9s payent 15 % de la prime, tandis que le gouvernement f\u00e9d\u00e9ral paye 85 % de la prime.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013Une fois le PSME mis en \u0153uvre, les employ\u00e9s ayant accumul\u00e9 plus de 26 semaines en cong\u00e9s de maladie auront le droit de reporter les jours exc\u00e9dentaires pour se doter d\u2019une couverture prolong\u00e9e \u00e0 100 % du remplacement du revenu avant de pouvoir recevoir des prestations d\u2019assurance-invalidit\u00e9 de longue dur\u00e9e (AILD).<br \/>\n\u2013 Les prestations d\u2019AILD s\u2019\u00e9l\u00e8vent \u00e0 70 % des revenus ant\u00e9rieurs \u00e0 l\u2019invalidit\u00e9.<\/p>\n\n<p>\u2013 Les employ\u00e9s payent 15 % de la prime, tandis que le gouvernement f\u00e9d\u00e9ral paye 85 % de la prime.<\/p>\n\n<p>Pour plus de d\u00e9tails sur les taux de prime du R\u00e9gime d\u2019assurance-invalidit\u00e9, cliquez ici : <a href=\"https:\/\/www.canada.ca\/fr\/secretariat-conseil-tresor\/services\/regimes-assurance\/regime-assurance-invalidite\/taux-prime.html\" target=\"_blank\" rel=\"noopener\">Taux de prime du R\u00e9gime d\u2019assurance-invalidit\u00e9 du SCT<\/a>.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9 (Conseil national mixte)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>AC) Assurance-vie<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>160 000 $, de base : Offerte aux membres civils en poste et retrait\u00e9s admissibles<\/p>\n\n<p>Assurance facultative de 198 000 $ offerte aux membres civils en poste et retrait\u00e9s qui souscrivent \u00e0 l\u2019assurance-vie de base.<\/p>\n\n<p>Assurance-vie pour personne \u00e0 charge : Offerte aux membres civils en poste et retrait\u00e9s qui souscrivent \u00e0 l\u2019assurance-vie de base<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Prestations suppl\u00e9mentaires de d\u00e9c\u00e8s obligatoire : montant \u00e9gal au double du salaire annuel de l\u2019employ\u00e9, arrondi au prochain multiple de 1000 $. Taux de cotisation = 0,15 $\/mois pour chaque tranche de 1 000 $ de salaire (couverture de base)<\/p>\n\n<p>Pour en savoir plus : <a href=\"https:\/\/www.tpsgc-pwgsc.gc.ca\/remuneration-compensation\/collectivite-community\/employeur-employer\/psd-adb-fra.html\" target=\"_blank\" rel=\"noopener\">Prestations suppl\u00e9mentaires de d\u00e9c\u00e8s de SPAC<\/a><\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9 (l\u00e9gislation)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>AD) Droits et prestations en mati\u00e8re de soins de sant\u00e9 et de soins dentaires<\/h3>\n\n<h4>GRC \/ CT-IPFPC<\/h4>\n\n<p>\u2013 Pas de p\u00e9riode d\u2019attente quand on passe de l\u2019admissibilit\u00e9 aux soins de sant\u00e9 et programmes de prestations de la GRC au R\u00e9gime de soins de sant\u00e9 de la fonction publique (RSSFP) du CNM<br \/>\n\u2013 Les num\u00e9ros de r\u00e9gime et de certificat de soins de sant\u00e9 demeureront les m\u00eames.<br \/>\n\u2013 Par contre, les num\u00e9ros de r\u00e9gime et de certificat de soins dentaires changeront, mais la transition se fera sans heurt, car il n\u2019y a pas de p\u00e9riode d\u2019attente.<\/p>\n\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9<\/li>\n<\/ul>\n\n<hr \/>\n<h3>AE) Programme d\u2019entra\u00eenement et de mode de vie<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Maximum de 60 minutes par semaine prises sur les heures de travail pour faire une activit\u00e9 physique (ce temps peut \u00eatre pris par segments de 15 \u00e0 30 minutes)<br \/>\nLe temps personnel consacr\u00e9 \u00e0 l\u2019activit\u00e9 physique doit correspondre au temps pass\u00e9 en dehors des heures normales de travail \u00e0 faire de l\u2019activit\u00e9 physique.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>Cette disposition n\u2019existe pas.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>Sous r\u00e9serve des n\u00e9cessit\u00e9s du service, les CM conservent cette condition tant qu\u2019ils demeurent au sein d\u2019une unit\u00e9 de n\u00e9gociation (groupe) repr\u00e9sent\u00e9e par l\u2019IPFPC, soit au sein de la GRC, ou qui deviendront des employ\u00e9s de SPC au moment de la conversion, aussi longtemps qu\u2019ils demeureront au service de SPC.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>AF) Prix de service continu<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>-20 ans : M\u00e9daille et certificat d\u2019anciennet\u00e9 de la GRC\/M\u00e9daille, \u00e9pinglette et certificat pour membres civils<br \/>\n-25 ans : Agrafe de bronze \u00e0 une \u00e9toile\/\u00e9pinglette pour membres civils<br \/>\n-30 ans : Agrafe d\u2019argent \u00e0 deux \u00e9toiles\/\u00e9pinglette pour membres civils<br \/>\n-35 ans : Agrafe d\u2019or \u00e0 trois \u00e9toiles\/\u00e9pinglette pour membres civils<br \/>\n-40 ans : Agrafe d\u2019or et d\u2019argent \u00e0 quatre \u00e9toiles\/\u00e9pinglette pour membres civils<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>-20 ans de service f\u00e9d\u00e9ral : Certificat pour souligner 20 ans de service, sign\u00e9 par le commissaire<br \/>\n-20 ans se service exclusif \u00e0 la GRC : \u00e9pinglette<br \/>\n-25, 30, 35, 40 ans : Parchemin informel soulignant l\u2019anniversaire c\u00e9l\u00e9br\u00e9<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>En dehors de ce qui peut \u00eatre n\u00e9goci\u00e9 (politique de la GRC)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>AG) Cong\u00e9 personnel\/cong\u00e9 pour b\u00e9n\u00e9volat<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Cette disposition n\u2019existe pas.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013Au total, 15 heures de cong\u00e9 pay\u00e9 pour des motifs personnels<\/p>\n\n<p>Ce cong\u00e9 peut \u00eatre pris par tranches de 3,75 ou de 7,5 heures.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n<hr \/>\n<h3>AH) Cong\u00e9 unique (anciennement appel\u00e9 \u00ab cong\u00e9 de mariage \u00bb)<\/h3>\n\n<div class=\"row three-col\">\n<div class=\"col-1 col-md-4\">\n<h4>GRC<\/h4>\n\n<p>Cette disposition n\u2019existe pas.<\/p>\n<\/div>\n\n<div class=\"col-2 col-md-4\">\n<h4>CT-IPFPC<\/h4>\n\n<p>\u2013Droit \u00e0 un cong\u00e9 pay\u00e9 unique de 37,5 heures le 1<sup>er<\/sup> jour suivant le mois du deuxi\u00e8me anniversaire de service d\u2019un employ\u00e9.<\/p>\n<\/div>\n\n<div class=\"col-3 col-md-4\">\n<h4>R\u00c9SULTAT<\/h4>\n\n<ul>\n\t<li>La convention collective s\u2019applique<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Quelques mots sur le tableau comparatif Le tableau ci-dessous ne contient pas toutes les dispositions des conventions collectives qui ne trouvent pas leur \u00e9quivalent dans les conditions de travail de la GRC. Il ne vise qu\u2019\u00e0 servir de guide aux membres civils de l\u2019IPFPC et ne refl\u00e8te peut-\u00eatre pas fid\u00e8lement les diff\u00e9rences entre membres civils &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2537],"group":[],"region":[],"employer":[],"chapter":[],"class_list":["post-61533","post","type-post","status-publish","format-standard","hentry","category-membres-civils-de-la-grc"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/61533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=61533"}],"version-history":[{"count":0,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/61533\/revisions"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=61533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=61533"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=61533"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=61533"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=61533"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=61533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}