{"id":58137,"date":"2026-01-16T00:00:00","date_gmt":"2026-01-16T00:00:00","guid":{"rendered":"https:\/\/pipsc.ca\/activite-diner-de-lipfpc-mises-a-jour-syndicales-et-retroaction-des-membres\/"},"modified":"2026-01-16T00:00:00","modified_gmt":"2026-01-16T00:00:00","slug":"activite-diner-de-lipfpc-mises-a-jour-syndicales-et-retroaction-des-membres","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/activite-diner-de-lipfpc-mises-a-jour-syndicales-et-retroaction-des-membres\/","title":{"rendered":"Activit\u00e9 d\u00eener de l\u2019IPFPC : mises \u00e0 jour syndicales et r\u00e9troaction des membres"},"content":{"rendered":"<div class=\"container\">\n<p>Joignez-vous \u00e0 nous pour une activit\u00e9 d\u00eener de l\u2019IPFPC.<\/p>\n\n<p><strong>Date :<\/strong> 29 janvier 2025<br \/>\n<strong>Heure :<\/strong> 12 h 00 <em>(pizza fournie)<\/em><\/p>\n\n<p><strong>Lieu :<\/strong><\/p>\n\n<ul>\n\t<li>Salle E, Place de la Cit\u00e9<\/li>\n\t<li>Salle 212, 395, rue Wellington<\/li>\n<\/ul>\n\n<p>Les membres peuvent \u00e9galement participer <a href=\"https:\/\/pipsc.zoom.us\/meeting\/register\/UEpFUUxBQA6XzTsOAwWL-g\" target=\"_blank\" rel=\"noopener\"><strong>par Zoom<\/strong><\/a>.<\/p>\n\n<p>En plus de souligner l\u2019engagement de nos d\u00e9l\u00e9gu\u00e9s syndicaux pass\u00e9s et actuels, nous sollicitons vos commentaires concernant le r\u00e9cent ajustement des effectifs et pr\u00e9senterons des mises \u00e0 jour g\u00e9n\u00e9rales sur les activit\u00e9s syndicales.<\/p>\n\n<p>Veuillez confirmer votre pr\u00e9sence <strong>en personne<\/strong> \u00e0 l\u2019un ou l\u2019autre des lieux <strong>au plus tard le 26 janvier<\/strong>.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Joignez-vous \u00e0 nous pour une activit\u00e9 d\u00eener de l\u2019IPFPC. Date : 29 janvier 2025 Heure : 12 h 00 (pizza fournie) Lieu : Salle E, Place de la Cit\u00e9 Salle 212, 395, rue Wellington Les membres peuvent \u00e9galement participer par Zoom. En plus de souligner l\u2019engagement de nos d\u00e9l\u00e9gu\u00e9s syndicaux pass\u00e9s et actuels, nous sollicitons &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2529],"group":[201,1304],"region":[],"employer":[],"chapter":[],"class_list":["post-58137","post","type-post","status-publish","format-standard","hentry","category-nouvelles","group-groupe-recherche-fr","group-re-rcn-bibliotheque-et-archives-canada-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/58137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=58137"}],"version-history":[{"count":0,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/58137\/revisions"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=58137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=58137"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=58137"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=58137"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=58137"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=58137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}