{"id":53541,"date":"2025-12-16T00:00:00","date_gmt":"2025-12-16T00:00:00","guid":{"rendered":"https:\/\/pipsc.ca\/compte-rendu-de-fin-dannee-de-lequipe-de-negociation-du-groupe-sp\/"},"modified":"2025-12-16T00:00:00","modified_gmt":"2025-12-16T00:00:00","slug":"compte-rendu-de-fin-dannee-de-lequipe-de-negociation-du-groupe-sp","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/compte-rendu-de-fin-dannee-de-lequipe-de-negociation-du-groupe-sp\/","title":{"rendered":"Compte rendu de fin d\u2019ann\u00e9e de l\u2019\u00e9quipe de n\u00e9gociation du groupe\u00a0SP"},"content":{"rendered":"<div class=\"container\">\n<p>L\u2019\u00e9quipe de n\u00e9gociation du groupe&nbsp;SP a \u00e9t\u00e9 tr\u00e8s occup\u00e9e par la formation \u00e0 la n\u00e9gociation, l\u2019\u00e9laboration des propositions de n\u00e9gociation et le sondage sur les n\u00e9gociations du groupe&nbsp;SP.<\/p>\n\n<p>Depuis notre <a href=\"https:\/\/pipsc.ca\/fr\/groupes\/sp\/compte-rendu-no-1-des-negociations-du-groupe-sp-nouvelle-equipe-nouvelle-direction\"><u>derni\u00e8re communication<\/u><\/a>, votre \u00e9quipe de n\u00e9gociation du groupe&nbsp;SP a \u00e9t\u00e9 tr\u00e8s active dans la pr\u00e9paration de la prochaine ronde de n\u00e9gociations.<\/p>\n\n<p>&nbsp;<\/p>\n\n<p>Au d\u00e9but du mois de septembre, toutes les \u00e9quipes de n\u00e9gociation des groupes de la fonction publique centrale et de certains organismes de l\u2019IPFPC ont particip\u00e9 \u00e0 une <a href=\"https:\/\/pipsc.ca\/fr\/nouvelles-et-enjeux\/annonces\/conference-de-formation-la-negociation\"><u>formation \u00e0 la n\u00e9gociation<\/u> <\/a>afin de s\u2019assurer que les \u00e9quipes de n\u00e9gociation disposent de la m\u00eame formation et pr\u00e9paration de base.<\/p>\n\n<p>&nbsp;<\/p>\n\n<p>La formation comprenait des s\u00e9minaires organis\u00e9s par le personnel de l\u2019IPFPC et des simulations de n\u00e9gociations interactives mises au point par l\u2019Universit\u00e9 Harvard afin d\u2019affiner les comp\u00e9tences en mati\u00e8re de strat\u00e9gie, de conclusion d\u2019ententes et de r\u00e8glement des diff\u00e9rends.<\/p>\n\n<p>L\u2019\u00e9quipe a pass\u00e9 plusieurs jours \u00e0 affiner les propositions qui seront pr\u00e9sent\u00e9es \u00e0 la conf\u00e9rence sur la n\u00e9gociation de janvier&nbsp;2026 et, finalement, au Conseil du Tr\u00e9sor \u00e0 l\u2019automne&nbsp;2026.<\/p>\n\n<p>Nous avons men\u00e9 une vaste campagne de mobilisation pour soutenir le sondage sur les n\u00e9gociations du groupe&nbsp;SP, y compris des assembl\u00e9es virtuelles avant le lancement du sondage. Les sous-groupes&nbsp;SP ont organis\u00e9 des s\u00e9ances d\u2019information, distribu\u00e9 des informations imprim\u00e9es aux membres sur leur lieu de travail et men\u00e9 une campagne de sensibilisation par t\u00e9l\u00e9phone et par courriel. Cela s\u2019est traduit par une participation record au sondage!&nbsp;<\/p>\n\n<p>Au total, nous avons constat\u00e9 une augmentation de pr\u00e8s de 85&nbsp;% par rapport au sondage sur les n\u00e9gociations pr\u00e9c\u00e9dent.<\/p>\n\n<p>&nbsp;<\/p>\n\n<p>Vos r\u00e9ponses au sondage sur les n\u00e9gociations ont montr\u00e9 que la majorit\u00e9 d\u2019entre vous pr\u00e9f\u00e9rait des communications plus courtes et plus concises sur les n\u00e9gociations.&nbsp;<\/p>\n\n<p>&nbsp;<\/p>\n\n<p>Pour ceux\/celles qui souhaitent obtenir des informations plus d\u00e9taill\u00e9es, vous trouverez des comptes rendus dans l\u2019espace Google Chat actif du groupe&nbsp;SP. Une adresse courriel de l\u2019IPFPC est n\u00e9cessaire pour s\u2019inscrire. Si vous n\u2019avez pas d\u2019adresse courriel @pipsc.ca, vous pouvez <a href=\"https:\/\/pipsc.ca\/fr\/outils-des-membres\/courriel\"><strong><u>en cr\u00e9er une sur notre site&nbsp;Web<\/u><\/strong><\/a>, puis envoyer un courriel \u00e0 <a href=\"mailto:ask_sp@pipsc.ca\"><strong><u>ask_sp@pipsc.ca<\/u><\/strong><\/a> pour \u00eatre ajout\u00e9\u00b7e \u00e0 l\u2019espace de discussion.<\/p>\n\n<p>&nbsp;<\/p>\n\n<p>Pour toute question, veuillez \u00e9crire \u00e0 Enzo&nbsp;Barresi \u00e0 <a href=\"mailto:ask_sp@pipsc.ca\"><strong><u>ask_sp@pipsc.ca<\/u><\/strong><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe de n\u00e9gociation du groupe&nbsp;SP a \u00e9t\u00e9 tr\u00e8s occup\u00e9e par la formation \u00e0 la n\u00e9gociation, l\u2019\u00e9laboration des propositions de n\u00e9gociation et le sondage sur les n\u00e9gociations du groupe&nbsp;SP. Depuis notre derni\u00e8re communication, votre \u00e9quipe de n\u00e9gociation du groupe&nbsp;SP a \u00e9t\u00e9 tr\u00e8s active dans la pr\u00e9paration de la prochaine ronde de n\u00e9gociations. &nbsp; Au d\u00e9but du &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71,2529],"group":[145],"region":[],"employer":[],"chapter":[],"class_list":["post-53541","post","type-post","status-publish","format-standard","hentry","category-negociation","category-nouvelles","group-groupe-sciences-appliquees-et-brevets-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/53541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=53541"}],"version-history":[{"count":0,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/53541\/revisions"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=53541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=53541"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=53541"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=53541"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=53541"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=53541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}