{"id":53535,"date":"2025-11-21T00:00:00","date_gmt":"2025-11-21T00:00:00","guid":{"rendered":"https:\/\/pipsc.ca\/negociations-du-groupe-nr-compte-rendu-no-2\/"},"modified":"2025-11-21T00:00:00","modified_gmt":"2025-11-21T00:00:00","slug":"negociations-du-groupe-nr-compte-rendu-no-2","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/negociations-du-groupe-nr-compte-rendu-no-2\/","title":{"rendered":"N\u00e9gociations du groupe NR \u2014 compte rendu no 2"},"content":{"rendered":"<div class=\"container\">\n<p>&nbsp;<\/p>\n<img decoding=\"async\" alt=\"NR Bargaining Team\" data-align=\"center\" data-caption=\"&lt;a href=&quot;https:\/\/pipsc.ca\/fr\/groupes\/nr\/equipe-de-negos&quot;&gt;Membres de l\u2019\u00e9quipe de n\u00e9gociation du groupe NR&lt;\/a&gt;&lt;br \/&gt;\nDe gauche \u00e0 droite&amp;nbsp;: John Britto Daniel Paulraj, Kimberly Hradecky, Thuc Van Quan, Jamie GoodMurphy, Philippe Ouimet, Michael Pauley, Cameron Smith, Gary Corbett, Shirley Tso, Luc Thibodeau (virtuellement), Sumeeta Fernando (absente)\" data-entity-type=\"file\" data-entity-uuid=\"f84479a3-13ef-4ce4-897f-2cef59f29a78\" src=\"\/sites\/default\/files\/inline-images\/Bargaining%20Team%20Photo.png\" \/>\n<p>&nbsp;<\/p>\n\n<p>Bonjour,<\/p>\n\n<p>Au d\u00e9but du mois de septembre 2025, l\u2019\u00e9quipe de n\u00e9gociation du groupe NR a particip\u00e9 \u00e0 la formation sur la n\u00e9gociation de l\u2019Institut professionnel de la fonction publique du Canada (IPFPC) \u00e0 Gatineau, au Qu\u00e9bec. Notre prochain objectif sera d\u2019\u00e9laborer un sondage pour le groupe NR qui comprendra des questions pos\u00e9es \u00e0 nos membres.<\/p>\n\n<p>Nous vous encourageons vivement \u00e0 informer les membres \u00e0 propos de ce prochain sondage et de l\u2019importance d\u2019y r\u00e9pondre. Cela permettra \u00e0 l\u2019\u00e9quipe de n\u00e9gociation d\u2019avoir un aper\u00e7u pr\u00e9cis des membres.<\/p>\n\n<p>Les r\u00e9sultats du sondage serviront \u00e0 d\u00e9finir nos priorit\u00e9s pour la prochaine ronde de n\u00e9gociations. Pour vous assurer de recevoir le sondage, v\u00e9rifiez que l\u2019Institut dispose bien de votre adresse courriel personnelle. Vous pouvez mettre \u00e0 jour vos coordonn\u00e9es sur <a href=\"https:\/\/pipsc.ca\/fr\/outils-des-membres\/changement-adresse\"><strong>notre site Web<\/strong><\/a>.<\/p>\n\n<p>Si vous avez des questions or des pr\u00e9ocupations, veuillez contacter l&#8217;\u00e9guipe de n\u00e9gociations NR au&nbsp;<a href=\"mailto:nr_barg_team@pipsc.ca\">nr_barg_team@pipsc.ca<\/a>. &nbsp;<\/p>\n\n<p>En toute solidarit\u00e9,<br \/>\nL\u2019\u00e9quipe de n\u00e9gociation du groupe NR<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Bonjour, Au d\u00e9but du mois de septembre 2025, l\u2019\u00e9quipe de n\u00e9gociation du groupe NR a particip\u00e9 \u00e0 la formation sur la n\u00e9gociation de l\u2019Institut professionnel de la fonction publique du Canada (IPFPC) \u00e0 Gatineau, au Qu\u00e9bec. Notre prochain objectif sera d\u2019\u00e9laborer un sondage pour le groupe NR qui comprendra des questions pos\u00e9es \u00e0 &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71,2529],"group":[196],"region":[],"employer":[],"chapter":[],"class_list":["post-53535","post","type-post","status-publish","format-standard","hentry","category-negociation","category-nouvelles","group-groupe-genie-architecture-et-arpentage-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/53535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=53535"}],"version-history":[{"count":0,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/53535\/revisions"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=53535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=53535"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=53535"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=53535"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=53535"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=53535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}