{"id":53371,"date":"2025-03-05T00:00:00","date_gmt":"2025-03-05T00:00:00","guid":{"rendered":"https:\/\/pipsc.ca\/resultats-des-elections-du-comite-executif-du-groupe-re-2025\/"},"modified":"2025-03-05T00:00:00","modified_gmt":"2025-03-05T00:00:00","slug":"resultats-des-elections-du-comite-executif-du-groupe-re-2025","status":"publish","type":"post","link":"https:\/\/pipsc.ca\/fr\/resultats-des-elections-du-comite-executif-du-groupe-re-2025\/","title":{"rendered":"R\u00e9sultats des \u00e9lections du Comit\u00e9 ex\u00e9cutif du groupe RE 2025"},"content":{"rendered":"<div class=\"container\">\n<p>Le Comit\u00e9 des \u00e9lections du groupe RE a le plaisir d\u2019annoncer les r\u00e9sultats des \u00e9lections<br \/>\nde 2025.<br \/>\n<br \/>\n\u00c0 la cl\u00f4ture des candidatures le 7&nbsp;f\u00e9vrier 2025, le Comit\u00e9 des \u00e9lections du groupe<br \/>\nRecherche&nbsp;2025 avait re\u00e7u 12&nbsp;candidatures valides pour 13&nbsp;postes. Par cons\u00e9quent,<br \/>\nconform\u00e9ment \u00e0 nos statuts, aucune \u00e9lection n\u2019\u00e9tait n\u00e9cessaire et les 12&nbsp;personnes<br \/>\ncandidates ont \u00e9t\u00e9 \u00e9lues par acclamation.<br \/>\n<br \/>\nLe Comit\u00e9 des \u00e9lections f\u00e9licite les personnes \u00e9lues suivantes et les remercie de leur<br \/>\nparticipation&nbsp;:<br \/>\n&nbsp;<\/p>\n\n<table class=\"Table\">\n\t<tbody>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p><strong>R\u00c9GION<\/strong><\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p><strong>NOM<\/strong><\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p>Atlantique<\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p>Nancy Shackell (SE)<\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p>Qu\u00e9bec<\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p>Jean B\u00e9rub\u00e9 (SE)<\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p>RCN<\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p>Kathleen Emberson (MA), Eric Hortop (MA),<\/p>\n\n\t\t\t<p>Matthew MacLeod (DS), Jason Rancourt (SE)<\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p>Ontario<\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p>Andrew Billyard (DS)<\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p>Prairies<\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p>Alebachew Demoz (SE), Mohammad Khakbazan (SE)<\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>\n\t\t\t<p>C.-B. et Yukon<\/p>\n\t\t\t<\/td>\n\t\t\t<td>\n\t\t\t<p>Chris Perry (HR), Nathaniel Newlands (SE),<\/p>\n\n\t\t\t<p>Xiaolan&nbsp;Wang (SE)<\/p>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n<p>&nbsp;<\/p>\n\n<p>Leur mandat de 3&nbsp;ans d\u00e9butera le 7&nbsp;juin 2025, jour de l\u2019assembl\u00e9e g\u00e9n\u00e9rale annuelle du<br \/>\ngroupe RE.<\/p>\n\n<p>Conform\u00e9ment \u00e0 l\u2019article&nbsp;8.4 des statuts du groupe RE, chaque r\u00e9gion d\u00e9finie dans les<br \/>\nstatuts de l\u2019Institut et chaque groupe composant le groupe RE sont repr\u00e9sent\u00e9s au sein<br \/>\nde l\u2019ex\u00e9cutif par au moins un\u00b7e membre \u00e9lu\u00b7e.<br \/>\n<br \/>\nEn toute solidarit\u00e9,<\/p>\n\n<p>Peter Hoyt, John MacFarlane, Madeena Sultana<br \/>\nComit\u00e9 des \u00e9lections du groupe Recherche, IPFPC<\/p>\n\n<p>&nbsp;<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le Comit\u00e9 des \u00e9lections du groupe RE a le plaisir d\u2019annoncer les r\u00e9sultats des \u00e9lections de 2025. \u00c0 la cl\u00f4ture des candidatures le 7&nbsp;f\u00e9vrier 2025, le Comit\u00e9 des \u00e9lections du groupe Recherche&nbsp;2025 avait re\u00e7u 12&nbsp;candidatures valides pour 13&nbsp;postes. Par cons\u00e9quent, conform\u00e9ment \u00e0 nos statuts, aucune \u00e9lection n\u2019\u00e9tait n\u00e9cessaire et les 12&nbsp;personnes candidates ont \u00e9t\u00e9 \u00e9lues &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2529],"group":[201],"region":[],"employer":[],"chapter":[],"class_list":["post-53371","post","type-post","status-publish","format-standard","hentry","category-nouvelles","group-groupe-recherche-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/53371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/comments?post=53371"}],"version-history":[{"count":0,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/posts\/53371\/revisions"}],"wp:attachment":[{"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/media?parent=53371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/categories?post=53371"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/group?post=53371"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/region?post=53371"},{"taxonomy":"employer","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/employer?post=53371"},{"taxonomy":"chapter","embeddable":true,"href":"https:\/\/pipsc.ca\/fr\/wp-json\/wp\/v2\/chapter?post=53371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}